{"id":1578,"date":"2012-11-07T18:19:35","date_gmt":"2012-11-07T17:19:35","guid":{"rendered":"http:\/\/www.hetregentbijnanooit.nl\/site\/?p=1578"},"modified":"2012-11-07T18:19:35","modified_gmt":"2012-11-07T17:19:35","slug":"07-11-2012","status":"publish","type":"post","link":"https:\/\/www.hetregentbijnanooit.nl\/site\/2012\/11\/07\/07-11-2012\/","title":{"rendered":"07-11-2012"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"http:\/\/www.hetregentbijnanooit.nl\/site\/grafiekjes\/\"><img decoding=\"async\" class=\"aligncenter\" title=\"nat - droog\" src=\"http:\/\/www.hetregentbijnanooit.nl\/site\/wp-content\/weerstrip-jaar-2\/rz2.jpg\" alt=\"nat - droog\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-1578","post","type-post","status-publish","format-standard","hentry","category-nat-droog"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p4aOTa-ps","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.hetregentbijnanooit.nl\/site\/wp-json\/wp\/v2\/posts\/1578"}],"collection":[{"href":"https:\/\/www.hetregentbijnanooit.nl\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hetregentbijnanooit.nl\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hetregentbijnanooit.nl\/site\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hetregentbijnanooit.nl\/site\/wp-json\/wp\/v2\/comments?post=1578"}],"version-history":[{"count":0,"href":"https:\/\/www.hetregentbijnanooit.nl\/site\/wp-json\/wp\/v2\/posts\/1578\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.hetregentbijnanooit.nl\/site\/wp-json\/wp\/v2\/media?parent=1578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hetregentbijnanooit.nl\/site\/wp-json\/wp\/v2\/categories?post=1578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hetregentbijnanooit.nl\/site\/wp-json\/wp\/v2\/tags?post=1578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}